{"id":468759,"date":"2015-11-04T07:04:49","date_gmt":"2015-11-04T07:04:49","guid":{"rendered":"https:\/\/visit-final.ddev.site\/de-zypern-entdecken\/de-kultur-religion-de-zypern-entdecken\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\/byzantine-museum-of-arsinoe-2\/"},"modified":"2015-11-04T07:04:49","modified_gmt":"2015-11-04T07:04:49","slug":"byzantine-museum-of-arsinoe-2","status":"publish","type":"post","link":"https:\/\/www.visitcyprus.com\/de\/de-zypern-entdecken\/de-kultur-religion-de-zypern-entdecken\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\/byzantine-museum-of-arsinoe-2\/","title":{"rendered":"Das byzantinische Museum von Arsinoe"},"content":{"rendered":"<p dir=\"ltr\">\n\tBei der Di\u00f6zese im malerischen Dorf Peristerona befindet sich das Byzantine Museum of Arsinoe mit einer der gr\u00f6\u00dften Sammlungen an Ikonen aus dem 13. bis 19. Jahrhundert. Zu den weiteren Exponaten geh\u00f6ren aus Holz geschnitzte Artefakte, die mit kirchlichen Zeremonien zusammenh\u00e4ngen, sowie einheimische und importierte Silber- und Metallartefakte, Textilien (wie z. B. Priestergew\u00e4nder und Bischofsroben aus dem 18. und 19. Jahrhundert), seltene B\u00fccher und Manuskripte.<\/p>\n<table align=\"center\" border=\"1\" cellpadding=\"3\" cellspacing=\"1\" style=\"width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 20%;\">\n\t\t\t\tBezirk:<\/td>\n<td>\n\t\t\t\tPafos (Paphos)<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 20%;\">\n\t\t\t\tAdresse:<\/td>\n<td>\n\t\t\t\tPeristerona, 9 km s\u00fcdlich von Pafos<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 20%;\">\n\t\t\t\tKontakt:<\/td>\n<td>\n\t\t\t\tTelefon: +357 26 352 515<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 20%;\">\n\t\t\t\t\u00d6ffnungszeiten:<\/td>\n<td>\n\t\t\t\t1. September bis 1. April: Montag &#8211; Freitag, 10:00 &#8211; 16:00 Uhr.<br \/>\n\t\t\t\t2. April bis 31. August: Montag &#8211; Freitag, 10:00 &#8211; 13:00 und 15:00 &#8211; 18:00 Uhr.<br \/>\n\t\t\t\tAm Wochenende geschlossen.<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 20%;\">\n\t\t\t\tWann:<\/td>\n<td>\n\t\t\t\tDas ganze Jahr \u00fcber.<br \/>\n\t\t\t\tAn gesetzlichen Feiertagen geschlossen.<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 20%;\">\n\t\t\t\tEintrittspreis:<\/td>\n<td>\n\t\t\t\t\u20ac2,00 pro Person.<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 20%;\">\n\t\t\t\tWebseite:<\/td>\n<td>\n\t\t\t\t<a href=\"http:\/\/www.mcw.gov.cy\/mcw\/da\/da.nsf\/DMLindex_en\/DMLindex_en?OpenDocument\" target=\"_blank\" rel=\"noopener\">www.mcw.gov.cy\/da<\/a><br \/>\n\t\t\t\t<a href=\"http:\/\/www.impaphou.org\/home_2.aspx\" target=\"_blank\" rel=\"noopener\">www.impaphou.org<\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 20%;\">\n\t\t\t\t&nbsp;<\/td>\n<td>\n\t\t\t\tDie \u00d6ffnungs- und Schlie\u00dfzeiten sowie der Eintrittspreis k\u00f6nnen sich ohne Vorank\u00fcndigung \u00e4ndern. Besuchern wird daher empfohlen, sich im Vorfeld zu informieren.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>\n\t&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bei der Di\u00f6zese im malerischen Dorf Peristerona befindet sich das Byzantine Museum of Arsinoe mit einer der gr\u00f6\u00dften Sammlungen an Ikonen aus dem 13. bis 19. Jahrhundert. Zu den weiteren [&hellip;]<\/p>\n","protected":false},"author":3508,"featured_media":396071,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6224],"tags":[7059],"class_list":["post-468759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-de-museen-galerien-de-kultur-religion-de-zypern-entdecken","tag-pafos-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Das byzantinische Museum von Arsinoe - Visit Cyprus<\/title>\n<meta name=\"description\" content=\"Situated at the Holy Bishopric in the picturesque village of Peristerona,.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.visitcyprus.com\/de\/de-zypern-entdecken\/de-kultur-religion-de-zypern-entdecken\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\/byzantine-museum-of-arsinoe-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Das byzantinische Museum von Arsinoe - Visit Cyprus\" \/>\n<meta property=\"og:description\" content=\"Situated at the Holy Bishopric in the picturesque village of Peristerona,.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.visitcyprus.com\/de\/de-zypern-entdecken\/de-kultur-religion-de-zypern-entdecken\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\/byzantine-museum-of-arsinoe-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Visit Cyprus\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VisitCyprus.cy\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-04T07:04:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.visitcyprus.com\/wp-content\/uploads\/2015\/11\/725ab2e5536ce3eac0a8dd17d083ff4e.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cconstantinou\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@visitcyprus\" \/>\n<meta name=\"twitter:site\" content=\"@visitcyprus\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"cconstantinou\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.visitcyprus.com\\\/de\\\/de-zypern-entdecken\\\/de-kultur-religion-de-zypern-entdecken\\\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\\\/byzantine-museum-of-arsinoe-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.visitcyprus.com\\\/de\\\/de-zypern-entdecken\\\/de-kultur-religion-de-zypern-entdecken\\\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\\\/byzantine-museum-of-arsinoe-2\\\/\"},\"author\":{\"name\":\"cconstantinou\",\"@id\":\"https:\\\/\\\/www.visitcyprus.com\\\/de\\\/#\\\/schema\\\/person\\\/0d6a627ad8d511316a3adb810bffce63\"},\"headline\":\"Das byzantinische Museum von Arsinoe\",\"datePublished\":\"2015-11-04T07:04:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.visitcyprus.com\\\/de\\\/de-zypern-entdecken\\\/de-kultur-religion-de-zypern-entdecken\\\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\\\/byzantine-museum-of-arsinoe-2\\\/\"},\"wordCount\":153,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.visitcyprus.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.visitcyprus.com\\\/de\\\/de-zypern-entdecken\\\/de-kultur-religion-de-zypern-entdecken\\\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\\\/byzantine-museum-of-arsinoe-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.visitcyprus.com\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/725ab2e5536ce3eac0a8dd17d083ff4e.jpg\",\"keywords\":[\"Pafos\"],\"articleSection\":[\"Museen &amp; Galerien\"],\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.visitcyprus.com\\\/de\\\/de-zypern-entdecken\\\/de-kultur-religion-de-zypern-entdecken\\\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\\\/byzantine-museum-of-arsinoe-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.visitcyprus.com\\\/de\\\/de-zypern-entdecken\\\/de-kultur-religion-de-zypern-entdecken\\\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\\\/byzantine-museum-of-arsinoe-2\\\/\",\"url\":\"https:\\\/\\\/www.visitcyprus.com\\\/de\\\/de-zypern-entdecken\\\/de-kultur-religion-de-zypern-entdecken\\\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\\\/byzantine-museum-of-arsinoe-2\\\/\",\"name\":\"Das byzantinische Museum von Arsinoe - Visit Cyprus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.visitcyprus.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.visitcyprus.com\\\/de\\\/de-zypern-entdecken\\\/de-kultur-religion-de-zypern-entdecken\\\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\\\/byzantine-museum-of-arsinoe-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.visitcyprus.com\\\/de\\\/de-zypern-entdecken\\\/de-kultur-religion-de-zypern-entdecken\\\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\\\/byzantine-museum-of-arsinoe-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.visitcyprus.com\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/725ab2e5536ce3eac0a8dd17d083ff4e.jpg\",\"datePublished\":\"2015-11-04T07:04:49+00:00\",\"description\":\"Situated at the Holy Bishopric in the picturesque village of Peristerona,.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.visitcyprus.com\\\/de\\\/de-zypern-entdecken\\\/de-kultur-religion-de-zypern-entdecken\\\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\\\/byzantine-museum-of-arsinoe-2\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.visitcyprus.com\\\/de\\\/de-zypern-entdecken\\\/de-kultur-religion-de-zypern-entdecken\\\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\\\/byzantine-museum-of-arsinoe-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.visitcyprus.com\\\/de\\\/de-zypern-entdecken\\\/de-kultur-religion-de-zypern-entdecken\\\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\\\/byzantine-museum-of-arsinoe-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.visitcyprus.com\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/725ab2e5536ce3eac0a8dd17d083ff4e.jpg\",\"contentUrl\":\"https:\\\/\\\/www.visitcyprus.com\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/725ab2e5536ce3eac0a8dd17d083ff4e.jpg\",\"width\":900,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.visitcyprus.com\\\/de\\\/de-zypern-entdecken\\\/de-kultur-religion-de-zypern-entdecken\\\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\\\/byzantine-museum-of-arsinoe-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.visitcyprus.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zypern entdecken\",\"item\":\"https:\\\/\\\/www.visitcyprus.com\\\/de\\\/de-zypern-entdecken\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kultur &amp; Religion\",\"item\":\"https:\\\/\\\/www.visitcyprus.com\\\/de\\\/de-zypern-entdecken\\\/de-kultur-religion-de-zypern-entdecken\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Museen &amp; Galerien\",\"item\":\"https:\\\/\\\/www.visitcyprus.com\\\/de\\\/de-zypern-entdecken\\\/de-kultur-religion-de-zypern-entdecken\\\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Das byzantinische Museum von Arsinoe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.visitcyprus.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.visitcyprus.com\\\/de\\\/\",\"name\":\"Visit Cyprus\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.visitcyprus.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.visitcyprus.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.visitcyprus.com\\\/de\\\/#organization\",\"name\":\"Visit Cyprus\",\"url\":\"https:\\\/\\\/www.visitcyprus.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.visitcyprus.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.visitcyprus.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/visitcyprus-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.visitcyprus.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/visitcyprus-logo.png\",\"width\":89,\"height\":167,\"caption\":\"Visit Cyprus\"},\"image\":{\"@id\":\"https:\\\/\\\/www.visitcyprus.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VisitCyprus.cy\\\/\",\"https:\\\/\\\/x.com\\\/visitcyprus\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.visitcyprus.com\\\/de\\\/#\\\/schema\\\/person\\\/0d6a627ad8d511316a3adb810bffce63\",\"name\":\"cconstantinou\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/425e0e6a7554c21f1e8e13ee3c136af6757c29da5e7aa6c1b5df5b80d68d4117?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/425e0e6a7554c21f1e8e13ee3c136af6757c29da5e7aa6c1b5df5b80d68d4117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/425e0e6a7554c21f1e8e13ee3c136af6757c29da5e7aa6c1b5df5b80d68d4117?s=96&d=mm&r=g\",\"caption\":\"cconstantinou\"},\"url\":\"https:\\\/\\\/www.visitcyprus.com\\\/de\\\/author\\\/cconstantinou\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Das byzantinische Museum von Arsinoe - Visit Cyprus","description":"Situated at the Holy Bishopric in the picturesque village of Peristerona,.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.visitcyprus.com\/de\/de-zypern-entdecken\/de-kultur-religion-de-zypern-entdecken\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\/byzantine-museum-of-arsinoe-2\/","og_locale":"de_DE","og_type":"article","og_title":"Das byzantinische Museum von Arsinoe - Visit Cyprus","og_description":"Situated at the Holy Bishopric in the picturesque village of Peristerona,.","og_url":"https:\/\/www.visitcyprus.com\/de\/de-zypern-entdecken\/de-kultur-religion-de-zypern-entdecken\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\/byzantine-museum-of-arsinoe-2\/","og_site_name":"Visit Cyprus","article_publisher":"https:\/\/www.facebook.com\/VisitCyprus.cy\/","article_published_time":"2015-11-04T07:04:49+00:00","og_image":[{"width":900,"height":400,"url":"https:\/\/www.visitcyprus.com\/wp-content\/uploads\/2015\/11\/725ab2e5536ce3eac0a8dd17d083ff4e.jpg","type":"image\/jpeg"}],"author":"cconstantinou","twitter_card":"summary_large_image","twitter_creator":"@visitcyprus","twitter_site":"@visitcyprus","twitter_misc":{"Written by":"cconstantinou","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.visitcyprus.com\/de\/de-zypern-entdecken\/de-kultur-religion-de-zypern-entdecken\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\/byzantine-museum-of-arsinoe-2\/#article","isPartOf":{"@id":"https:\/\/www.visitcyprus.com\/de\/de-zypern-entdecken\/de-kultur-religion-de-zypern-entdecken\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\/byzantine-museum-of-arsinoe-2\/"},"author":{"name":"cconstantinou","@id":"https:\/\/www.visitcyprus.com\/de\/#\/schema\/person\/0d6a627ad8d511316a3adb810bffce63"},"headline":"Das byzantinische Museum von Arsinoe","datePublished":"2015-11-04T07:04:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.visitcyprus.com\/de\/de-zypern-entdecken\/de-kultur-religion-de-zypern-entdecken\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\/byzantine-museum-of-arsinoe-2\/"},"wordCount":153,"commentCount":0,"publisher":{"@id":"https:\/\/www.visitcyprus.com\/de\/#organization"},"image":{"@id":"https:\/\/www.visitcyprus.com\/de\/de-zypern-entdecken\/de-kultur-religion-de-zypern-entdecken\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\/byzantine-museum-of-arsinoe-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.visitcyprus.com\/wp-content\/uploads\/2015\/11\/725ab2e5536ce3eac0a8dd17d083ff4e.jpg","keywords":["Pafos"],"articleSection":["Museen &amp; Galerien"],"inLanguage":"de-DE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.visitcyprus.com\/de\/de-zypern-entdecken\/de-kultur-religion-de-zypern-entdecken\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\/byzantine-museum-of-arsinoe-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.visitcyprus.com\/de\/de-zypern-entdecken\/de-kultur-religion-de-zypern-entdecken\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\/byzantine-museum-of-arsinoe-2\/","url":"https:\/\/www.visitcyprus.com\/de\/de-zypern-entdecken\/de-kultur-religion-de-zypern-entdecken\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\/byzantine-museum-of-arsinoe-2\/","name":"Das byzantinische Museum von Arsinoe - Visit Cyprus","isPartOf":{"@id":"https:\/\/www.visitcyprus.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.visitcyprus.com\/de\/de-zypern-entdecken\/de-kultur-religion-de-zypern-entdecken\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\/byzantine-museum-of-arsinoe-2\/#primaryimage"},"image":{"@id":"https:\/\/www.visitcyprus.com\/de\/de-zypern-entdecken\/de-kultur-religion-de-zypern-entdecken\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\/byzantine-museum-of-arsinoe-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.visitcyprus.com\/wp-content\/uploads\/2015\/11\/725ab2e5536ce3eac0a8dd17d083ff4e.jpg","datePublished":"2015-11-04T07:04:49+00:00","description":"Situated at the Holy Bishopric in the picturesque village of Peristerona,.","breadcrumb":{"@id":"https:\/\/www.visitcyprus.com\/de\/de-zypern-entdecken\/de-kultur-religion-de-zypern-entdecken\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\/byzantine-museum-of-arsinoe-2\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.visitcyprus.com\/de\/de-zypern-entdecken\/de-kultur-religion-de-zypern-entdecken\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\/byzantine-museum-of-arsinoe-2\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.visitcyprus.com\/de\/de-zypern-entdecken\/de-kultur-religion-de-zypern-entdecken\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\/byzantine-museum-of-arsinoe-2\/#primaryimage","url":"https:\/\/www.visitcyprus.com\/wp-content\/uploads\/2015\/11\/725ab2e5536ce3eac0a8dd17d083ff4e.jpg","contentUrl":"https:\/\/www.visitcyprus.com\/wp-content\/uploads\/2015\/11\/725ab2e5536ce3eac0a8dd17d083ff4e.jpg","width":900,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.visitcyprus.com\/de\/de-zypern-entdecken\/de-kultur-religion-de-zypern-entdecken\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\/byzantine-museum-of-arsinoe-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.visitcyprus.com\/de\/"},{"@type":"ListItem","position":2,"name":"Zypern entdecken","item":"https:\/\/www.visitcyprus.com\/de\/de-zypern-entdecken\/"},{"@type":"ListItem","position":3,"name":"Kultur &amp; Religion","item":"https:\/\/www.visitcyprus.com\/de\/de-zypern-entdecken\/de-kultur-religion-de-zypern-entdecken\/"},{"@type":"ListItem","position":4,"name":"Museen &amp; Galerien","item":"https:\/\/www.visitcyprus.com\/de\/de-zypern-entdecken\/de-kultur-religion-de-zypern-entdecken\/de-museen-galerien-de-kultur-religion-de-zypern-entdecken\/"},{"@type":"ListItem","position":5,"name":"Das byzantinische Museum von Arsinoe"}]},{"@type":"WebSite","@id":"https:\/\/www.visitcyprus.com\/de\/#website","url":"https:\/\/www.visitcyprus.com\/de\/","name":"Visit Cyprus","description":"","publisher":{"@id":"https:\/\/www.visitcyprus.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.visitcyprus.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.visitcyprus.com\/de\/#organization","name":"Visit Cyprus","url":"https:\/\/www.visitcyprus.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.visitcyprus.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.visitcyprus.com\/wp-content\/uploads\/2024\/04\/visitcyprus-logo.png","contentUrl":"https:\/\/www.visitcyprus.com\/wp-content\/uploads\/2024\/04\/visitcyprus-logo.png","width":89,"height":167,"caption":"Visit Cyprus"},"image":{"@id":"https:\/\/www.visitcyprus.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VisitCyprus.cy\/","https:\/\/x.com\/visitcyprus"]},{"@type":"Person","@id":"https:\/\/www.visitcyprus.com\/de\/#\/schema\/person\/0d6a627ad8d511316a3adb810bffce63","name":"cconstantinou","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/425e0e6a7554c21f1e8e13ee3c136af6757c29da5e7aa6c1b5df5b80d68d4117?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/425e0e6a7554c21f1e8e13ee3c136af6757c29da5e7aa6c1b5df5b80d68d4117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/425e0e6a7554c21f1e8e13ee3c136af6757c29da5e7aa6c1b5df5b80d68d4117?s=96&d=mm&r=g","caption":"cconstantinou"},"url":"https:\/\/www.visitcyprus.com\/de\/author\/cconstantinou\/"}]}},"_links":{"self":[{"href":"https:\/\/www.visitcyprus.com\/de\/wp-json\/wp\/v2\/posts\/468759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.visitcyprus.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.visitcyprus.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.visitcyprus.com\/de\/wp-json\/wp\/v2\/users\/3508"}],"replies":[{"embeddable":true,"href":"https:\/\/www.visitcyprus.com\/de\/wp-json\/wp\/v2\/comments?post=468759"}],"version-history":[{"count":0,"href":"https:\/\/www.visitcyprus.com\/de\/wp-json\/wp\/v2\/posts\/468759\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.visitcyprus.com\/de\/wp-json\/wp\/v2\/media\/396071"}],"wp:attachment":[{"href":"https:\/\/www.visitcyprus.com\/de\/wp-json\/wp\/v2\/media?parent=468759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.visitcyprus.com\/de\/wp-json\/wp\/v2\/categories?post=468759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.visitcyprus.com\/de\/wp-json\/wp\/v2\/tags?post=468759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}